{"id":435,"date":"2017-08-21T13:26:29","date_gmt":"2017-08-21T13:26:29","guid":{"rendered":"https:\/\/identalcentelles.com\/?page_id=435"},"modified":"2022-08-30T14:15:27","modified_gmt":"2022-08-30T14:15:27","slug":"la-clinica","status":"publish","type":"page","link":"https:\/\/identalcentelles.com\/index.php\/la-clinica\/","title":{"rendered":"La Cl\u00ednica"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_hover-box clearfix\" data-effect=\"slideDown\">\n\t\t\t<div class=\"vu_hb-wrapper\">\n\t\t\t\t<div class=\"vu_hb-holder embed-responsive embed-responsive-3by2\">\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"vu_hb-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/clinica_exterior.png\" class=\"attachment-dentalpress_ratio-3:2 size-dentalpress_ratio-3:2\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/clinica_exterior.png 600w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/clinica_exterior-300x200.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"vu_hb-container\" style=\"background-color:rgba(80,176,227,0.75);\">\n\t\t\t\t\t\t<span class=\"vu_hb-content\">\n\t\t\t\t\t\t\t<h4 class=\"m-t-0 m-b-0\" style=\"text-align: center; line-height: 22px;\"><span style=\"color: #ffffff;\">Exterior<\/span><\/h4>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_hover-box clearfix\" data-effect=\"slideDown\">\n\t\t\t<div class=\"vu_hb-wrapper\">\n\t\t\t\t<div class=\"vu_hb-holder embed-responsive embed-responsive-3by2\">\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"vu_hb-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/sala_espera_id_centelles.png\" class=\"attachment-dentalpress_ratio-3:2 size-dentalpress_ratio-3:2\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/sala_espera_id_centelles.png 600w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/sala_espera_id_centelles-300x200.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"vu_hb-container\" style=\"background-color:rgba(80,176,227,0.75);\">\n\t\t\t\t\t\t<span class=\"vu_hb-content\">\n\t\t\t\t\t\t\t<h4 class=\"m-t-0 m-b-0\" style=\"text-align: center; line-height: 22px;\"><span style=\"color: #ffffff;\">Sala d&#8217;espera<\/span><\/h4>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_hover-box clearfix\" data-effect=\"slideDown\">\n\t\t\t<div class=\"vu_hb-wrapper\">\n\t\t\t\t<div class=\"vu_hb-holder embed-responsive embed-responsive-3by2\">\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"vu_hb-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/lavabo_adaptat_id_centelles.png\" class=\"attachment-dentalpress_ratio-3:2 size-dentalpress_ratio-3:2\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/lavabo_adaptat_id_centelles.png 600w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/lavabo_adaptat_id_centelles-300x200.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"vu_hb-container\" style=\"background-color:rgba(80,176,227,0.75);\">\n\t\t\t\t\t\t<span class=\"vu_hb-content\">\n\t\t\t\t\t\t\t<h4 class=\"m-t-0 m-b-0\" style=\"text-align: center; line-height: 22px;\"><span style=\"color: #ffffff;\">Lavabo adaptat<\/span><\/h4>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][\/vc_row][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_hover-box clearfix\" data-effect=\"slideDown\">\n\t\t\t<div class=\"vu_hb-wrapper\">\n\t\t\t\t<div class=\"vu_hb-holder embed-responsive embed-responsive-3by2\">\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"vu_hb-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/recepcio_id_dental_centelles.png\" class=\"attachment-dentalpress_ratio-3:2 size-dentalpress_ratio-3:2\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/recepcio_id_dental_centelles.png 600w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/recepcio_id_dental_centelles-300x200.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"vu_hb-container\" style=\"background-color:rgba(80,176,227,0.75);\">\n\t\t\t\t\t\t<span class=\"vu_hb-content\">\n\t\t\t\t\t\t\t<h4 class=\"m-t-0 m-b-0\" style=\"text-align: center; line-height: 22px;\"><span style=\"color: #ffffff;\">Recepci\u00f3<\/span><\/h4>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_hover-box clearfix\" data-effect=\"slideDown\">\n\t\t\t<div class=\"vu_hb-wrapper\">\n\t\t\t\t<div class=\"vu_hb-holder embed-responsive embed-responsive-3by2\">\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"vu_hb-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/box_identalcentelles.png\" class=\"attachment-dentalpress_ratio-3:2 size-dentalpress_ratio-3:2\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/box_identalcentelles.png 600w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/box_identalcentelles-300x200.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"vu_hb-container\" style=\"background-color:rgba(80,176,227,0.75);\">\n\t\t\t\t\t\t<span class=\"vu_hb-content\">\n\t\t\t\t\t\t\t<h4 class=\"m-t-0 m-b-0\" style=\"text-align: center; line-height: 22px;\"><span style=\"color: #ffffff;\">Box<\/span><\/h4>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_hover-box clearfix\" data-effect=\"slideDown\">\n\t\t\t<div class=\"vu_hb-wrapper\">\n\t\t\t\t<div class=\"vu_hb-holder embed-responsive embed-responsive-3by2\">\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"vu_hb-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/darrera_box_institut_dental.png\" class=\"attachment-dentalpress_ratio-3:2 size-dentalpress_ratio-3:2\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/darrera_box_institut_dental.png 600w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/darrera_box_institut_dental-300x200.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"vu_hb-container\" style=\"background-color:rgba(80,176,227,0.75);\">\n\t\t\t\t\t\t<span class=\"vu_hb-content\">\n\t\t\t\t\t\t\t<h4 class=\"m-t-0 m-b-0\" style=\"text-align: center; line-height: 22px;\"><span style=\"color: #ffffff;\">Box 2<\/span><\/h4>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;][\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;][\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;][\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;][\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":14,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/pages\/435"}],"collection":[{"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/comments?post=435"}],"version-history":[{"count":17,"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/pages\/435\/revisions"}],"predecessor-version":[{"id":2196,"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/pages\/435\/revisions\/2196"}],"wp:attachment":[{"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/media?parent=435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}