{"id":73,"date":"2017-08-17T15:23:06","date_gmt":"2017-08-17T15:23:06","guid":{"rendered":"https:\/\/identalcentelles.com\/?page_id=73"},"modified":"2022-09-07T11:07:36","modified_gmt":"2022-09-07T11:07:36","slug":"home","status":"publish","type":"page","link":"https:\/\/identalcentelles.com\/","title":{"rendered":"Inici"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section content_layout=&#8221;full&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;no-padding&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221;][vc_column_text]\n\t\t\t<!-- START DentalPress Horizontal Slider REVOLUTION SLIDER 6.6.20 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_1_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_1_1\" style=\"\" data-version=\"6.6.20\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-2\" data-title=\"Slide\" data-thumb=\"\/\/www.dentistesdemolins.com\/wp-content\/uploads\/2019\/04\/HOME_PAGE_DENTISTAS_3_destacado.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/identalcentelles.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" width=\"1920\" height=\"1080\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/identalcentelles.com\/wp-content\/uploads\/2022\/05\/institut_dental_centelles.png\" data-parallax=\"off\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-2-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#58585a\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:r;xo:39px;yo:210px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:16;l:26;fw:500;a:right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:360px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"y:50px;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;st:1629.8608398438;sp:500;sR:1629.8608398438;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"y:50px;o:0;tp:600;st:8700.0006103516;sR:6570.1397705078;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;font-family:'Quicksand';\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-2-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#007aff\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:70px;yo:67px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:44;l:45;fw:700;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:12;r:15;b:12;l:15;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;st:639.93041992188;sR:639.93041992188;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;tp:600;st:w;sR:8060.0701904297;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;background-color:rgba(186,186,186,0);font-family:'Montserrat';cursor:pointer;\"\n\t\t\t\t\t\t\t>La nostra <br>experi\u00e8ncia <br>\nens avala \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-2-layer-6\" \n\t\t\t\t\t\t\t\tclass=\"rev-btn\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"rgba(255,255,255,1)\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:87px;yo:239px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:17;l:17;a:center;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:simplelink;target:_self;url:https:\/\/identalcentelles.com\/index.php\/cita-online\/;'\n\t\t\t\t\t\t\t\tdata-rsp_bd=\"off\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:12;r:35;b:12;l:35;\"\n\t\t\t\t\t\t\t\tdata-border=\"bor:3px,3px,3px,3px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;st:639.93041992188;sR:639.93041992188;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;tp:600;st:w;sR:8060.0701904297;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#000;bgc:#fff;boc:#000;bor:3px,3px,3px,3px;bos:solid;oX:50;oY:50;sp:0;e:none;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;background-color:rgba(0,0,0,0.75);font-family:'Montserrat';cursor:pointer;outline:none;box-shadow:none;box-sizing:border-box;-moz-box-sizing:border-box;-webkit-box-sizing:border-box;\"\n\t\t\t\t\t\t\t>Demana cita pr\u00e8via \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-1\" data-title=\"Slide\" data-thumb=\"\/\/www.dentistesdemolins.com\/wp-content\/uploads\/revslider\/dentalpress-horizontal-slider\/slider-4-slide-1.jpg\" data-duration=\"9000\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/identalcentelles.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" width=\"1920\" height=\"1080\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/identalcentelles.com\/wp-content\/uploads\/2022\/05\/institut_dental_centelles_somriure.png\" data-parallax=\"off\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-1-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:63px;yo:235px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:44;l:45;fw:700;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:441px;h:214px;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:12;r:15;b:12;l:15;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"y:-50px;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;st:1209.8956298828;sp:500;sR:1209.8956298828;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"y:-50px;o:0;tp:600;st:w;sp:469.965;sR:7290.1049804688;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;background-color:rgba(187,10,36,0);font-family:'Montserrat';cursor:pointer;\"\n\t\t\t\t\t\t\t>El somriure \u00e9s<br>\nel llenguatge<br>\ninternacional<br>\nde les persones \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-1-layer-3\" \n\t\t\t\t\t\t\t\tclass=\"rev-btn\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"rgba(255,255,255,1)\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:80px;yo:185px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:17;l:17;a:right;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:simplelink;target:_self;url:https:\/\/identalcentelles.com\/index.php\/sobre-nosaltres\/;'\n\t\t\t\t\t\t\t\tdata-rsp_bd=\"off\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:12;r:35;b:12;l:35;\"\n\t\t\t\t\t\t\t\tdata-border=\"bor:3px,3px,3px,3px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;st:1209.8956298828;sR:1209.8956298828;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;tp:600;st:w;sR:7490.1049804688;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#000;bgc:#fff;boc:#000;bor:3px,3px,3px,3px;bos:solid;oX:50;oY:50;sp:0;e:none;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;background-color:rgba(0,122,255,0.75);font-family:'Montserrat';cursor:pointer;outline:none;box-shadow:none;box-sizing:border-box;-moz-box-sizing:border-box;-webkit-box-sizing:border-box;\"\n\t\t\t\t\t\t\t>Sobre nosaltres \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-4\" data-title=\"Slide\" data-thumb=\"\/\/www.dentistesdemolins.com\/wp-content\/uploads\/2019\/04\/HOME_PAGE_DENTISTAS_2_destacado.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/identalcentelles.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" width=\"1920\" height=\"1080\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/identalcentelles.com\/wp-content\/uploads\/2022\/05\/institut_dental_centelles_invisalign.png\" data-parallax=\"off\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-4-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#007aff\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:r;xo:723px;yo:89px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:50;l:45;fw:700;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:442px;h:205px;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:12;r:15;b:12;l:15;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"y:-50px;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;st:1629.8608398438;sp:500;sR:1629.8608398438;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"y:-50px;o:0;tp:600;st:w;sR:6870.1397705078;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;background-color:rgba(187,10,36,0);font-family:'Montserrat';\"\n\t\t\t\t\t\t\t>Posem la <br>tecnologia <br>m\u00e9s avan\u00e7ada <br>al teu servei \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-4-layer-3\" \n\t\t\t\t\t\t\t\tclass=\"rev-btn\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"rgba(255,255,255,1)\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:90px;yo:308px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:17;l:17;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:simplelink;target:_self;url:https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/;'\n\t\t\t\t\t\t\t\tdata-rsp_bd=\"off\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:12;r:35;b:12;l:35;\"\n\t\t\t\t\t\t\t\tdata-border=\"bor:3px,3px,3px,3px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;st:1650;sR:1650;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;tp:600;st:w;sR:7050.0006103516;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#000;bgc:#fff;bor:3px,3px,3px,3px;oX:50;oY:50;sp:0;e:none;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;background-color:rgba(0,0,0,0.75);font-family:'Montserrat';outline:none;box-shadow:none;box-sizing:border-box;-moz-box-sizing:border-box;-webkit-box-sizing:border-box;\"\n\t\t\t\t\t\t\t>Descubreix el que t'oferim \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-3\" data-title=\"Slide\" data-thumb=\"\/\/www.dentistesdemolins.com\/wp-content\/uploads\/2019\/04\/HOME_PAGE_DENTISTAS_4_destacado.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/identalcentelles.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" width=\"1920\" height=\"1080\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/identalcentelles.com\/wp-content\/uploads\/2022\/05\/institut_dental_centelles_protesi.png\" data-parallax=\"off\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-3-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:809px;yo:228px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:44;l:45;fw:700;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:412px;h:250px;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:12;r:15;b:12;l:15;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"y:-50px;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;st:1000;sp:500;sR:1000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"y:-50px;o:0;tp:600;st:w;sR:7500.0006103516;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;background-color:rgba(187,10,36,0);font-family:'Montserrat';cursor:pointer;\"\n\t\t\t\t\t\t\t>Al teu costat<br> en la cura de  <br\/>la salut dental \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-3-layer-3\" \n\t\t\t\t\t\t\t\tclass=\"rev-btn\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"rgba(255,255,255,1)\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:827px;yo:173px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:17;l:17;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:simplelink;target:_self;url:https:\/\/identalcentelles.com\/index.php\/la-clinica\/;'\n\t\t\t\t\t\t\t\tdata-rsp_bd=\"off\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:12;r:35;b:12;l:35;\"\n\t\t\t\t\t\t\t\tdata-border=\"bor:3px,3px,3px,3px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;st:1000;sR:1000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;tp:600;st:w;sR:7700.0006103516;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#000;bgc:#fff;boc:#000;bor:3px,3px,3px,3px;bos:solid;oX:50;oY:50;sp:0;e:none;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;background-color:rgba(0,122,255,0.75);font-family:'Montserrat';cursor:pointer;outline:none;box-shadow:none;box-sizing:border-box;-moz-box-sizing:border-box;-webkit-box-sizing:border-box;\"\n\t\t\t\t\t\t\t>La nostra cl\u00ednica \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t\t<rs-static-layers class=\"rs-stl-visible\"><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-1-layer-3\" \n\t\t\t\t\t\t\t\tclass=\"tp-shape tp-shapewrapper rs-layer-static\"\n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:b;\"\n\t\t\t\t\t\t\t\tdata-text=\"fw:300;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:1500px;h:120px;\"\n\t\t\t\t\t\t\t\tdata-vbility=\"t,t,f,f\"\n\t\t\t\t\t\t\t\tdata-onslides=\"s:1;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;st:0;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;tp:600;st:w;sR:8700;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:11;background-color:rgba(88,88,90,0.3);\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\t\t\t\t\t--><\/rs-static-layers>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_1_1',rl:[1240,1024,778,480],el:[],gw:[1240,1024,778,480],gh:[600,600,500,400],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider11\"]!==undefined) {window.RS_MODULES.modules[\"revslider11\"].once = false;window.revapi1 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t\t<div class=\"vu_icon-box-2 vu_ib-type-icon vu_ib-style-1 clearfix\">\n\t\t\t\t<div class=\"vu_ib-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"vu_fi vu_fi-chat\"><\/i>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t\t<h5 class=\"vu_ib-title\">Avantatges en la teva 1\u00aa visita<\/h5>\n\t\t\t\t\t<div class=\"vu_ib-description\"><p>Pressupost sense comprom\u00eds<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t\t<div class=\"vu_icon-box-2 vu_ib-type-icon vu_ib-style-1 clearfix\">\n\t\t\t\t<div class=\"vu_ib-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"vu_fi vu_fi-caries\"><\/i>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t\t<h5 class=\"vu_ib-title\">\u00daltima tecnologia en salut dental<\/h5>\n\t\t\t\t\t<div class=\"vu_ib-description\"><p>Assegurant el teu somriure<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t\t<div class=\"vu_icon-box-2 vu_ib-type-icon vu_ib-style-1 clearfix\">\n\t\t\t\t<div class=\"vu_ib-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"vu_fi vu_fi-records-1\"><\/i>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t\t<h5 class=\"vu_ib-title\">Atenci\u00f3 personalitzada<\/h5>\n\t\t\t\t\t<div class=\"vu_ib-description\"><p>Tracte familiar i de qualitat<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t[\/vc_column][\/vc_row][vc_section content_layout=&#8221;full&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;p-b-0&#8243; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/2&#8243;]\t\t<header class=\"vu_heading vu_h-style-1 vu_h-alignment-left m-b-25 vu_custom_6191244\">\n\t\t\t\t\t\t\t<style scoped>\n\t\t\t\t\t\t\t\t\t\t\t.vu_heading.vu_custom_6191244 .vu_h-heading { color: #2eb0cf}\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\n\t\t\t\t\t\t\t<h2 class=\"vu_h-heading\">Sobre nosaltres<\/h2>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"vu_h-subheading\">\n\t\t\t\t\t<p>Benvinguts a la nostra cl\u00ednica dental<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/header>\n\t[vc_column_text el_class=&#8221;m-b-25&#8243;]<\/p>\n<p class=\"p1\"><span class=\"s1\">A Institut Dental Centelles volem ajudar-te a millorar el teu somriure posant a la teva disposici\u00f3 un grup de professionals altament qualificats i amb una llarga experi\u00e8ncia en el sector, oferir-te la millor garantia m\u00e8dica. Comptem amb l&#8217;equipament i la tecnologia m\u00e9s avan\u00e7ada per a la millor diagnosi i tractament.<\/span><\/p>\n<p>A Institut Dental Centelles som un equip d&#8217;odont\u00f2legs professionals que treballa dia a dia per aconseguir el m\u00e0xim benestar dels nostres pacients.<\/p>\n<p>Som un equip que est\u00e0 constantment formant-se perqu\u00e8 la teva salut bucal estigui en les millors mans. El nostre tracte \u00e9s personalitzat ja que abans de res som una cl\u00ednica familiar.[\/vc_column_text]\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/sobre-nosaltres\/\" title=\"http:\/\/SOBRE%20NOSALTRES\" target=\"_blank\" class=\"vu_button btn btn-inverse btn-sm btn-primary btn-icon m-b-30\">\n\t\t\t<span>M\u00e9s informaci\u00f3<\/span><i class=\"vu_fi vu_fi-arrow-right\"><\/i>\t\t<\/a>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/2&#8243;]\t\t<div class=\"vu_image-box clearfix\">\n\t\t\t<div class=\"vu_ib-image\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/clinica_exterior.png\" class=\"attachment-dentalpress_ratio-3:2 size-dentalpress_ratio-3:2\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/clinica_exterior.png 600w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2022\/08\/clinica_exterior-300x200.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t<\/div>\n\n\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t<h4 class=\"vu_ib-title\">\n\t\t\t\t\t\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][\/vc_row][\/vc_section][vc_section content_layout=&#8221;full&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;p-b-0&#8243; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;true&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;middle&#8221; animation_delay=&#8221;&#8221; width=&#8221;2\/3&#8243; el_class=&#8221;col-sm-8&#8243;]\t\t<header class=\"vu_heading vu_h-style-1 vu_h-alignment-left vu_custom_9396340\">\n\t\t\t\t\t\t\t<style scoped>\n\t\t\t\t\t\t\t\t\t\t\t.vu_heading.vu_custom_9396340 .vu_h-heading { color: #2eb0cf}\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\n\t\t\t\t\t\t\t<h2 class=\"vu_h-heading\">Tractaments i Serveis<\/h2>\n\t\t\t\n\t\t\t\t\t<\/header>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;middle&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243; el_class=&#8221;col-sm-4 text-right vu_text-left-md&#8221;]\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"\" target=\"_self\" class=\"vu_button btn btn-inverse btn-sm btn-secondary btn-icon m-b-30\">\n\t\t\t<span>Veure tots els serveis<\/span><i class=\"vu_fi vu_fi-arrow-right\"><\/i>\t\t<\/a>\n\t[\/vc_column][\/vc_row][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_image-box clearfix\">\n\t\t\t<div class=\"vu_ib-image\">\n\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"ODONTOLOGIA GENERAL\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ODONTOLOGIA_GENERAL-.jpg\" class=\"attachment-dentalpress_ratio-2:1 size-dentalpress_ratio-2:1\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ODONTOLOGIA_GENERAL-.jpg 800w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ODONTOLOGIA_GENERAL--300x150.jpg 300w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ODONTOLOGIA_GENERAL--768x384.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\t\t\t<\/div>\n\n\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t<h4 class=\"vu_ib-title\">\n\t\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"ODONTOLOGIA GENERAL\" target=\"_self\">ODONTOLOGIA GENERAL<\/a>\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_image-box clearfix\">\n\t\t\t<div class=\"vu_ib-image\">\n\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"PROTESIS\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/PROTESIS.jpg\" class=\"attachment-dentalpress_ratio-2:1 size-dentalpress_ratio-2:1\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/PROTESIS.jpg 800w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/PROTESIS-300x150.jpg 300w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/PROTESIS-768x384.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\t\t\t<\/div>\n\n\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t<h4 class=\"vu_ib-title\">\n\t\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"PROTESIS\" target=\"_self\">PROTESIS<\/a>\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_image-box clearfix\">\n\t\t\t<div class=\"vu_ib-image\">\n\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/IMPLANTOLOGIA_CIRURGIA.jpg\" class=\"attachment-dentalpress_ratio-2:1 size-dentalpress_ratio-2:1\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/IMPLANTOLOGIA_CIRURGIA.jpg 800w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/IMPLANTOLOGIA_CIRURGIA-300x150.jpg 300w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/IMPLANTOLOGIA_CIRURGIA-768x384.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\t\t\t<\/div>\n\n\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t<h4 class=\"vu_ib-title\">\n\t\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"\" target=\"_self\">IMPLANTOLOGIA I CIRURGIA ORAL<\/a>\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][\/vc_row][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_image-box clearfix\">\n\t\t\t<div class=\"vu_ib-image\">\n\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/PERIODONCIA.jpg\" class=\"attachment-dentalpress_ratio-2:1 size-dentalpress_ratio-2:1\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/PERIODONCIA.jpg 800w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/PERIODONCIA-300x150.jpg 300w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/PERIODONCIA-768x384.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\t\t\t<\/div>\n\n\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t<h4 class=\"vu_ib-title\">\n\t\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"\" target=\"_self\">PERIODONCIA<\/a>\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_image-box clearfix\">\n\t\t\t<div class=\"vu_ib-image\">\n\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"ENDODONCIA\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ENDODONCIA.jpg\" class=\"attachment-dentalpress_ratio-2:1 size-dentalpress_ratio-2:1\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ENDODONCIA.jpg 800w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ENDODONCIA-300x150.jpg 300w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ENDODONCIA-768x384.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\t\t\t<\/div>\n\n\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t<h4 class=\"vu_ib-title\">\n\t\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"ENDODONCIA\" target=\"_self\">ENDODONCIA<\/a>\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_image-box clearfix\">\n\t\t\t<div class=\"vu_ib-image\">\n\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ODONTOPEDIATRIA.jpg\" class=\"attachment-dentalpress_ratio-2:1 size-dentalpress_ratio-2:1\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ODONTOPEDIATRIA.jpg 800w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ODONTOPEDIATRIA-300x150.jpg 300w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ODONTOPEDIATRIA-768x384.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\t\t\t<\/div>\n\n\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t<h4 class=\"vu_ib-title\">\n\t\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"\" target=\"_self\">ODONTOPEDIATRIA<\/a>\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][\/vc_row][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_image-box clearfix\">\n\t\t\t<div class=\"vu_ib-image\">\n\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ORTODONCIA.jpg\" class=\"attachment-dentalpress_ratio-2:1 size-dentalpress_ratio-2:1\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ORTODONCIA.jpg 800w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ORTODONCIA-300x150.jpg 300w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ORTODONCIA-768x384.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\t\t\t<\/div>\n\n\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t<h4 class=\"vu_ib-title\">\n\t\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"\" target=\"_self\">ORTODONCIA<\/a>\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_image-box clearfix\">\n\t\t\t<div class=\"vu_ib-image\">\n\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"EST\u00c9TICA DENTAL\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ESTETICA_DENTAL.jpg\" class=\"attachment-dentalpress_ratio-2:1 size-dentalpress_ratio-2:1\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ESTETICA_DENTAL.jpg 800w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ESTETICA_DENTAL-300x150.jpg 300w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ESTETICA_DENTAL-768x384.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\t\t\t<\/div>\n\n\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t<h4 class=\"vu_ib-title\">\n\t\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"EST\u00c9TICA DENTAL\" target=\"_self\">EST\u00c8TICA DENTAL<\/a>\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_image-box clearfix\">\n\t\t\t<div class=\"vu_ib-image\">\n\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ODONTOLOGIA_DEPORTE.jpg\" class=\"attachment-dentalpress_ratio-2:1 size-dentalpress_ratio-2:1\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ODONTOLOGIA_DEPORTE.jpg 800w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ODONTOLOGIA_DEPORTE-300x150.jpg 300w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ODONTOLOGIA_DEPORTE-768x384.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\t\t\t<\/div>\n\n\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t<h4 class=\"vu_ib-title\">\n\t\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"\" target=\"_self\">ODONTOLOGIA DE L&#039;ESPORT<\/a>\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][\/vc_row][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_image-box clearfix\">\n\t\t\t<div class=\"vu_ib-image\">\n\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"PATOLOGIA ATM (BRUXISMO)\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/PATOLOGIA_ATM.jpg\" class=\"attachment-dentalpress_ratio-2:1 size-dentalpress_ratio-2:1\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/PATOLOGIA_ATM.jpg 800w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/PATOLOGIA_ATM-300x150.jpg 300w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/PATOLOGIA_ATM-768x384.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\t\t\t<\/div>\n\n\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t<h4 class=\"vu_ib-title\">\n\t\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"PATOLOGIA ATM (BRUXISMO)\" target=\"_self\">PATOLOGIA ATM (BRUXISME)<\/a>\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;]\t\t<div class=\"vu_image-box clearfix\">\n\t\t\t<div class=\"vu_ib-image\">\n\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ESTETICA_FACIAL.jpg\" class=\"attachment-dentalpress_ratio-2:1 size-dentalpress_ratio-2:1\" alt=\"\" srcset=\"https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ESTETICA_FACIAL.jpg 800w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ESTETICA_FACIAL-300x150.jpg 300w, https:\/\/identalcentelles.com\/wp-content\/uploads\/2019\/04\/ESTETICA_FACIAL-768x384.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\t\t\t<\/div>\n\n\t\t\t<div class=\"vu_ib-content\">\n\t\t\t\t<h4 class=\"vu_ib-title\">\n\t\t\t\t\t<a href=\"https:\/\/identalcentelles.com\/index.php\/tractaments-i-serveis\/\" title=\"\" target=\"_self\">EST\u00c8TICA FACIAL<\/a>\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t[\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section content_layout=&#8221;boxed&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;1500&#8243; color_overlay=&#8221;rgba(0,0,0,0.1)&#8221; enable_parallax=&#8221;true&#8221; enable_pattern=&#8221;&#8221; css=&#8221;.vc_custom_1554656632990{padding-top: 50px !important;padding-bottom: 50px !important;}&#8221;][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;7\/12&#8243;][vc_column_text el_class=&#8221;m-b-20&#8243;]<\/p>\n<h3 class=\"m-t-0 m-b-0\" style=\"text-align: left;\"><span style=\"color: #2eb0cf;\">Ofertes especials<\/span><\/h3>\n<h3 class=\"m-t-0 m-b-0\" style=\"text-align: left;\"><span style=\"color: #000000;\">Subscriu-te al nostre newsletter<\/span><\/h3>\n<p>[\/vc_column_text][\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;5\/12&#8243;][\/vc_column][\/vc_row][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;7\/12&#8243;][vc_column_text el_class=&#8221;m-b-20&#8243;]\n\t\t<div class=\"vu_newsletter\">\n\t\t\t\n\t\t\t<form class=\"vu_n-form vu_frm-ajax vu_clear-fields\" role=\"form\">\n\t\t\t\t<div class=\"hide\">\n\t\t\t\t\t<input type=\"hidden\" name=\"action\" value=\"vu_newsletter\">\n\t\t\t\t\t<input type=\"hidden\" name=\"_wpnonce\" value=\"d16b8f20bd\">\n\t\t\t\t<\/div>\n\n\t\t\t\t<input type=\"email\" name=\"email\" class=\"form-control\" placeholder=\"Adre\u00e7a de mail\">\n\t\t\t\t<button type=\"submit\" class=\"vu_n-button fa fa-paper-plane\"><\/button>\n\n\t\t\t\t<div class=\"clear\"><\/div>\n\n\t\t\t\t<div class=\"vu_msg\" data-class=\"m-t-15 m-b-0\"><\/div>\n\t\t\t<\/form>\n\t\t<\/div>\n\n\n\t\t[\/vc_column_text][\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;5\/12&#8243;][\/vc_column][\/vc_row][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;7\/12&#8243;][vc_column_text el_class=&#8221;m-b-0&#8243;]<\/p>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\">En proporcionar-nos el vostre correu electr\u00f2nic, accepteu els termes del nostre<\/span><span style=\"color: #000000;\"><br \/>\n<\/span><span style=\"color: #000000;\"><a href=\"https:\/\/identalcentelles.com\/index.php\/vis-legal-politica-de-privacitat-i-us-de-les-cookies\/\" target=\"_blank\" rel=\"noopener noreferrer\">Av\u00eds legal i termes d&#8217;\u00fas<\/a><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;5\/12&#8243;][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_section content_layout=&#8221;full&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;no-padding&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221;][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_row content_layout=&#8221;boxed&#8221; equal_height=&#8221;&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;&#8221; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; color_overlay=&#8221;&#8221; enable_parallax=&#8221;&#8221; enable_pattern=&#8221;&#8221;][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;][\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;][\/vc_column][vc_column layout=&#8221;normal&#8221; vertical_align=&#8221;top&#8221; animation_delay=&#8221;&#8221; width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][vc_section content_layout=&#8221;full&#8221; animation_delay=&#8221;&#8221; disable=&#8221;&#8221; id=&#8221;&#8221; class=&#8221;p-b-0&#8243; bg_type=&#8221;image&#8221; bg_image=&#8221;&#8221; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":13,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/pages\/73"}],"collection":[{"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/comments?post=73"}],"version-history":[{"count":76,"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/pages\/73\/revisions"}],"predecessor-version":[{"id":2174,"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/pages\/73\/revisions\/2174"}],"wp:attachment":[{"href":"https:\/\/identalcentelles.com\/index.php\/wp-json\/wp\/v2\/media?parent=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}